{"id":27,"date":"2020-09-21T22:11:09","date_gmt":"2020-09-21T20:11:09","guid":{"rendered":"https:\/\/www.humeurs.be\/boutique\/?page_id=27"},"modified":"2020-09-21T22:11:09","modified_gmt":"2020-09-21T20:11:09","slug":"homepage","status":"publish","type":"page","link":"https:\/\/www.humeurs.be\/boutique\/homepage\/","title":{"rendered":"Homepage"},"content":{"rendered":"\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wp-block-cover alignfull\" style=\"background-image:url(https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/hero-scaled.jpg);background-color:#ffffff\"><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n\t\t\t\t\t<h1 class=\"wp-block-heading\" style=\"text-align:center\">Welcome<\/h1>\n\t\t\t\t\t\n\n\t\t\t\t\t\n\t\t\t\t\t<p style=\"color:#000000;text-align:center\" class=\"has-text-color\">This is your homepage which is what most visitors will see when they first visit your shop.<\/p>\n\t\t\t\t\t\n\n\t\t\t\t\t\n\t\t\t\t\t<p style=\"color:#000000;text-align:center\" class=\"has-text-color\">You can change this text by editing the \u00ab\u00a0Welcome\u00a0\u00bb page via the \u00ab\u00a0Pages\u00a0\u00bb menu in your dashboard.<\/p>\n\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\n\t\t\t\t\n\n\t\t\t\t\n\t\t\t\t<h2 class=\"wp-block-heading\" style=\"text-align:center\">Shop by Category<\/h2>\n\t\t\t\t\n\n\t\t\t\t<div class=\"woocommerce columns-3\"><ul class=\"products columns-3\">\n<li class=\"product-category product first\">\n\t<a aria-label=\"Visit product category BD\" href=\"https:\/\/www.humeurs.be\/boutique\/categorie-produit\/bd\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/woocommerce-placeholder-324x486.png\" alt=\"BD\" width=\"324\" height=\"486\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tBD <mark class=\"count\">(4)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product\">\n\t<a aria-label=\"Visit product category Cartoon\" href=\"https:\/\/www.humeurs.be\/boutique\/categorie-produit\/cartoon\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/woocommerce-placeholder-324x486.png\" alt=\"Cartoon\" width=\"324\" height=\"486\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tCartoon <mark class=\"count\">(7)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<li class=\"product-category product last\">\n\t<a aria-label=\"Visit product category Dessin de presse\" href=\"https:\/\/www.humeurs.be\/boutique\/categorie-produit\/dessin-de-presse\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/woocommerce-placeholder-324x486.png\" alt=\"Dessin de presse\" width=\"324\" height=\"486\" \/>\t\t<h2 class=\"woocommerce-loop-category__title\">\n\t\t\tDessin de presse <mark class=\"count\">(7)<\/mark>\t\t<\/h2>\n\t\t<\/a><\/li>\n<\/ul>\n<\/div>\n\n\n\t\t\t\t\n\t\t\t\t<h2 class=\"wp-block-heading\" style=\"text-align:center\">New In<\/h2>\n\t\t\t\t\n\n\t\t\t\t<div data-block-name=\"woocommerce\/product-new\" data-columns=\"4\" class=\"wc-block-grid wp-block-product-new wp-block-woocommerce-product-new wc-block-product-new has-4-columns has-multiple-rows\"><ul class=\"wc-block-grid__products\"><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/de-gre-ou-de-force-le-choix-de-franz-2026\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2026\/05\/DGODF-2026-LeChoixDeFranz-Couverture-Web-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"De gr\u00e9 ou de force - BD - 2026\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">De gr\u00e9 ou de force &#8211; Le choix de Franz (2026)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=286\" aria-label=\"Add to cart: &ldquo;De gr\u00e9 ou de force - Le choix de Franz (2026)&rdquo;\" data-quantity=\"1\" data-product_id=\"286\" data-product_sku=\"9782931190333\" data-price=\"20\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2024\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"351\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Spa \u00e0 l&#039;heure US - 2024\" srcset=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250.jpg 250w, https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250-214x300.jpg 214w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Spa \u00e0 l&rsquo;heure US (2024)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=237\" aria-label=\"Add to cart: &ldquo;Spa \u00e0 l&#039;heure US (2024)&rdquo;\" data-quantity=\"1\" data-product_id=\"237\" data-product_sku=\"9782931190159\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gardons-le-sourire-les-humeurs-doli-t7-2023\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2023\/10\/LesHumeursDOli-2023-GardonsLeSourire-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Gardons le sourire ! Les humeurs d&#039;Oli - 2023\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Gardons le sourire ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T7 (2023)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">19,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=192\" aria-label=\"Add to cart: &ldquo;Gardons le sourire ! - Les Humeurs d&#039;Oli - T7 (2023)&rdquo;\" data-quantity=\"1\" data-product_id=\"192\" data-product_sku=\"9782960335200\" data-price=\"19.9\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gare-au-crash-les-humeurs-doli-t6-2022\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2022\/11\/LesHumeursDOli-2022-GareAuCrash-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Gare au Crash ! - Les Humeurs d&#039;Oli 2022\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Gare au Crash ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T6 (2022)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">19,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gare-au-crash-les-humeurs-doli-t6-2022\/\" aria-label=\"En savoir plus sur &ldquo;Gare au Crash ! - Les Humeurs d&#039;Oli - T6 (2022)&rdquo;\" data-quantity=\"1\" data-product_id=\"168\" data-product_sku=\"9782380758702\" data-price=\"19.9\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/a-leau-le-monde-les-humeurs-doli-t5\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2021\/10\/LesHumeursDOli-2021-ALEauLeMonde-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\u00c0 l&#039;eau le monde - Les Humeurs d&#039;Oli\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">\u00c0 l&rsquo;eau le monde ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T5 (2021)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=139\" aria-label=\"Add to cart: &ldquo;\u00c0 l&#039;eau le monde ! - Les Humeurs d&#039;Oli - T5 (2021)&rdquo;\" data-quantity=\"1\" data-product_id=\"139\" data-product_sku=\"9782507057190\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/hautes-fagnes-contes-et-legendes-2016\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/HautesFagnes-ContesEtLegendes-2017-500-EPUISE-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BD Hautes Fagnes Contes et L\u00e9gendes\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Hautes Fagnes &#8211; Contes et L\u00e9gendes (2016)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/hautes-fagnes-contes-et-legendes-2016\/\" aria-label=\"En savoir plus sur &ldquo;Hautes Fagnes - Contes et L\u00e9gendes (2016)&rdquo;\" data-quantity=\"1\" data-product_id=\"64\" data-product_sku=\"9782390100591\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2018\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/SpaALHeureUS-2018-500-EPUISE-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BD Spa \u00e0 l&#039;heure US - Epuis\u00e9\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Spa \u00e0 l&rsquo;heure US (2018)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2018\/\" aria-label=\"En savoir plus sur &ldquo;Spa \u00e0 l&#039;heure US (2018)&rdquo;\" data-quantity=\"1\" data-product_id=\"62\" data-product_sku=\"9782390101260\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/cest-pas-gagne-les-humeurs-doli-t1-2017\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2017-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"C&#039;est pas gagn\u00e9...\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">C&rsquo;est pas gagn\u00e9&#8230; &#8211; Les Humeurs d&rsquo;Oli &#8211; T1 (2017)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">12,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 12,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=60\" aria-label=\"Add to cart: &ldquo;C&#039;est pas gagn\u00e9... - Les Humeurs d&#039;Oli - T1 (2017)&rdquo;\" data-quantity=\"1\" data-product_id=\"60\" data-product_sku=\"9782507055479\" data-price=\"12\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/sacres-champions-les-humeurs-doli-t2-2018\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2018-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Sacr\u00e9s champions !\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Sacr\u00e9s champions ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T2 (2018)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">13,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 13,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=57\" aria-label=\"Add to cart: &ldquo;Sacr\u00e9s champions ! - Les Humeurs d&#039;Oli - T2 (2018)&rdquo;\" data-quantity=\"1\" data-product_id=\"57\" data-product_sku=\"9782507056063\" data-price=\"13\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/vox-populi-les-humeurs-doli-t3\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2019-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Voc Populi\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Vox Populi &#8211; Les Humeurs d&rsquo;Oli &#8211; T3 (2019)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=56\" aria-label=\"Add to cart: &ldquo;Vox Populi - Les Humeurs d&#039;Oli - T3 (2019)&rdquo;\" data-quantity=\"1\" data-product_id=\"56\" data-product_sku=\"9782507056544\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/masquarade-les-humeurs-doli-t4\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2020-Masquarade-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Masquarade - Les Humeurs d&#039;Oli 2020\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Masquarade &#8211; Les Humeurs d&rsquo;Oli &#8211; T4 (2020)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=53\" aria-label=\"Add to cart: &ldquo;Masquarade - Les Humeurs d&#039;Oli - T4 (2020)&rdquo;\" data-quantity=\"1\" data-product_id=\"53\" data-product_sku=\"9782507056834\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><\/ul><\/div>\n\n\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<h2 class=\"wp-block-heading\" style=\"text-align:center\">We Recommend<\/h2>\n\t\t\t\t\t\n\n\t\t\t\t\t\n\t\t\t\t\n\n\t\t\t\t\n\t\t\t\t<h2 class=\"wp-block-heading\" style=\"text-align:center\">Fan Favorites<\/h2>\n\t\t\t\t\n\n\t\t\t\t<div data-block-name=\"woocommerce\/product-top-rated\" data-columns=\"4\" class=\"wc-block-grid wp-block-product-top-rated wp-block-woocommerce-product-top-rated wc-block-product-top-rated has-4-columns has-multiple-rows\"><ul class=\"wc-block-grid__products\"><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/de-gre-ou-de-force-le-choix-de-franz-2026\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2026\/05\/DGODF-2026-LeChoixDeFranz-Couverture-Web-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"De gr\u00e9 ou de force - BD - 2026\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">De gr\u00e9 ou de force &#8211; Le choix de Franz (2026)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=286\" aria-label=\"Add to cart: &ldquo;De gr\u00e9 ou de force - Le choix de Franz (2026)&rdquo;\" data-quantity=\"1\" data-product_id=\"286\" data-product_sku=\"9782931190333\" data-price=\"20\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2024\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"351\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Spa \u00e0 l&#039;heure US - 2024\" srcset=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250.jpg 250w, https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250-214x300.jpg 214w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Spa \u00e0 l&rsquo;heure US (2024)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=237\" aria-label=\"Add to cart: &ldquo;Spa \u00e0 l&#039;heure US (2024)&rdquo;\" data-quantity=\"1\" data-product_id=\"237\" data-product_sku=\"9782931190159\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gardons-le-sourire-les-humeurs-doli-t7-2023\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2023\/10\/LesHumeursDOli-2023-GardonsLeSourire-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Gardons le sourire ! Les humeurs d&#039;Oli - 2023\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Gardons le sourire ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T7 (2023)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">19,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=192\" aria-label=\"Add to cart: &ldquo;Gardons le sourire ! - Les Humeurs d&#039;Oli - T7 (2023)&rdquo;\" data-quantity=\"1\" data-product_id=\"192\" data-product_sku=\"9782960335200\" data-price=\"19.9\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gare-au-crash-les-humeurs-doli-t6-2022\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2022\/11\/LesHumeursDOli-2022-GareAuCrash-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Gare au Crash ! - Les Humeurs d&#039;Oli 2022\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Gare au Crash ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T6 (2022)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">19,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gare-au-crash-les-humeurs-doli-t6-2022\/\" aria-label=\"En savoir plus sur &ldquo;Gare au Crash ! - Les Humeurs d&#039;Oli - T6 (2022)&rdquo;\" data-quantity=\"1\" data-product_id=\"168\" data-product_sku=\"9782380758702\" data-price=\"19.9\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/a-leau-le-monde-les-humeurs-doli-t5\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2021\/10\/LesHumeursDOli-2021-ALEauLeMonde-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\u00c0 l&#039;eau le monde - Les Humeurs d&#039;Oli\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">\u00c0 l&rsquo;eau le monde ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T5 (2021)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=139\" aria-label=\"Add to cart: &ldquo;\u00c0 l&#039;eau le monde ! - Les Humeurs d&#039;Oli - T5 (2021)&rdquo;\" data-quantity=\"1\" data-product_id=\"139\" data-product_sku=\"9782507057190\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/hautes-fagnes-contes-et-legendes-2016\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/HautesFagnes-ContesEtLegendes-2017-500-EPUISE-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BD Hautes Fagnes Contes et L\u00e9gendes\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Hautes Fagnes &#8211; Contes et L\u00e9gendes (2016)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/hautes-fagnes-contes-et-legendes-2016\/\" aria-label=\"En savoir plus sur &ldquo;Hautes Fagnes - Contes et L\u00e9gendes (2016)&rdquo;\" data-quantity=\"1\" data-product_id=\"64\" data-product_sku=\"9782390100591\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2018\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/SpaALHeureUS-2018-500-EPUISE-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BD Spa \u00e0 l&#039;heure US - Epuis\u00e9\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Spa \u00e0 l&rsquo;heure US (2018)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2018\/\" aria-label=\"En savoir plus sur &ldquo;Spa \u00e0 l&#039;heure US (2018)&rdquo;\" data-quantity=\"1\" data-product_id=\"62\" data-product_sku=\"9782390101260\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/cest-pas-gagne-les-humeurs-doli-t1-2017\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2017-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"C&#039;est pas gagn\u00e9...\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">C&rsquo;est pas gagn\u00e9&#8230; &#8211; Les Humeurs d&rsquo;Oli &#8211; T1 (2017)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">12,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 12,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=60\" aria-label=\"Add to cart: &ldquo;C&#039;est pas gagn\u00e9... - Les Humeurs d&#039;Oli - T1 (2017)&rdquo;\" data-quantity=\"1\" data-product_id=\"60\" data-product_sku=\"9782507055479\" data-price=\"12\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/sacres-champions-les-humeurs-doli-t2-2018\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2018-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Sacr\u00e9s champions !\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Sacr\u00e9s champions ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T2 (2018)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">13,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 13,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=57\" aria-label=\"Add to cart: &ldquo;Sacr\u00e9s champions ! - Les Humeurs d&#039;Oli - T2 (2018)&rdquo;\" data-quantity=\"1\" data-product_id=\"57\" data-product_sku=\"9782507056063\" data-price=\"13\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/vox-populi-les-humeurs-doli-t3\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2019-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Voc Populi\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Vox Populi &#8211; Les Humeurs d&rsquo;Oli &#8211; T3 (2019)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=56\" aria-label=\"Add to cart: &ldquo;Vox Populi - Les Humeurs d&#039;Oli - T3 (2019)&rdquo;\" data-quantity=\"1\" data-product_id=\"56\" data-product_sku=\"9782507056544\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/masquarade-les-humeurs-doli-t4\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2020-Masquarade-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Masquarade - Les Humeurs d&#039;Oli 2020\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Masquarade &#8211; Les Humeurs d&rsquo;Oli &#8211; T4 (2020)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=53\" aria-label=\"Add to cart: &ldquo;Masquarade - Les Humeurs d&#039;Oli - T4 (2020)&rdquo;\" data-quantity=\"1\" data-product_id=\"53\" data-product_sku=\"9782507056834\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><\/ul><\/div>\n\n\t\t\t\t\n\t\t\t\t<h2 class=\"wp-block-heading\" style=\"text-align:center\">On Sale<\/h2>\n\t\t\t\t\n\n\t\t\t\t<div data-block-name=\"woocommerce\/product-on-sale\" data-columns=\"4\" class=\"wc-block-grid wp-block-product-on-sale wp-block-woocommerce-product-on-sale wc-block-product-on-sale has-4-columns has-multiple-rows\"><ul class=\"wc-block-grid__products\"><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/a-leau-le-monde-les-humeurs-doli-t5\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2021\/10\/LesHumeursDOli-2021-ALEauLeMonde-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\u00c0 l&#039;eau le monde - Les Humeurs d&#039;Oli\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">\u00c0 l&rsquo;eau le monde ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T5 (2021)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=139\" aria-label=\"Add to cart: &ldquo;\u00c0 l&#039;eau le monde ! - Les Humeurs d&#039;Oli - T5 (2021)&rdquo;\" data-quantity=\"1\" data-product_id=\"139\" data-product_sku=\"9782507057190\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/cest-pas-gagne-les-humeurs-doli-t1-2017\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2017-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"C&#039;est pas gagn\u00e9...\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">C&rsquo;est pas gagn\u00e9&#8230; &#8211; Les Humeurs d&rsquo;Oli &#8211; T1 (2017)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">12,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 12,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=60\" aria-label=\"Add to cart: &ldquo;C&#039;est pas gagn\u00e9... - Les Humeurs d&#039;Oli - T1 (2017)&rdquo;\" data-quantity=\"1\" data-product_id=\"60\" data-product_sku=\"9782507055479\" data-price=\"12\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/sacres-champions-les-humeurs-doli-t2-2018\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2018-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Sacr\u00e9s champions !\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Sacr\u00e9s champions ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T2 (2018)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">13,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 13,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=57\" aria-label=\"Add to cart: &ldquo;Sacr\u00e9s champions ! - Les Humeurs d&#039;Oli - T2 (2018)&rdquo;\" data-quantity=\"1\" data-product_id=\"57\" data-product_sku=\"9782507056063\" data-price=\"13\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/vox-populi-les-humeurs-doli-t3\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2019-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Voc Populi\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Vox Populi &#8211; Les Humeurs d&rsquo;Oli &#8211; T3 (2019)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=56\" aria-label=\"Add to cart: &ldquo;Vox Populi - Les Humeurs d&#039;Oli - T3 (2019)&rdquo;\" data-quantity=\"1\" data-product_id=\"56\" data-product_sku=\"9782507056544\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/masquarade-les-humeurs-doli-t4\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2020-Masquarade-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Masquarade - Les Humeurs d&#039;Oli 2020\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Masquarade &#8211; Les Humeurs d&rsquo;Oli &#8211; T4 (2020)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=53\" aria-label=\"Add to cart: &ldquo;Masquarade - Les Humeurs d&#039;Oli - T4 (2020)&rdquo;\" data-quantity=\"1\" data-product_id=\"53\" data-product_sku=\"9782507056834\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><\/ul><\/div>\n\n\t\t\t\t\n\t\t\t\t<h2 class=\"wp-block-heading\" style=\"text-align:center\">Best Sellers<\/h2>\n\t\t\t\t\n\n\t\t\t\t<div data-block-name=\"woocommerce\/product-best-sellers\" data-columns=\"4\" class=\"wc-block-grid wp-block-product-best-sellers wp-block-woocommerce-product-best-sellers wc-block-product-best-sellers has-4-columns has-multiple-rows\"><ul class=\"wc-block-grid__products\"><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/masquarade-les-humeurs-doli-t4\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2020-Masquarade-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Masquarade - Les Humeurs d&#039;Oli 2020\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Masquarade &#8211; Les Humeurs d&rsquo;Oli &#8211; T4 (2020)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=53\" aria-label=\"Add to cart: &ldquo;Masquarade - Les Humeurs d&#039;Oli - T4 (2020)&rdquo;\" data-quantity=\"1\" data-product_id=\"53\" data-product_sku=\"9782507056834\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/a-leau-le-monde-les-humeurs-doli-t5\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2021\/10\/LesHumeursDOli-2021-ALEauLeMonde-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\u00c0 l&#039;eau le monde - Les Humeurs d&#039;Oli\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">\u00c0 l&rsquo;eau le monde ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T5 (2021)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=139\" aria-label=\"Add to cart: &ldquo;\u00c0 l&#039;eau le monde ! - Les Humeurs d&#039;Oli - T5 (2021)&rdquo;\" data-quantity=\"1\" data-product_id=\"139\" data-product_sku=\"9782507057190\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2024\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"351\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Spa \u00e0 l&#039;heure US - 2024\" srcset=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250.jpg 250w, https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2024\/05\/Spa-a-l-heure-US-2024-Cover-250-214x300.jpg 214w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Spa \u00e0 l&rsquo;heure US (2024)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=237\" aria-label=\"Add to cart: &ldquo;Spa \u00e0 l&#039;heure US (2024)&rdquo;\" data-quantity=\"1\" data-product_id=\"237\" data-product_sku=\"9782931190159\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gardons-le-sourire-les-humeurs-doli-t7-2023\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2023\/10\/LesHumeursDOli-2023-GardonsLeSourire-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Gardons le sourire ! Les humeurs d&#039;Oli - 2023\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Gardons le sourire ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T7 (2023)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">19,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=192\" aria-label=\"Add to cart: &ldquo;Gardons le sourire ! - Les Humeurs d&#039;Oli - T7 (2023)&rdquo;\" data-quantity=\"1\" data-product_id=\"192\" data-product_sku=\"9782960335200\" data-price=\"19.9\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/vox-populi-les-humeurs-doli-t3\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2019-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Voc Populi\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Vox Populi &#8211; Les Humeurs d&rsquo;Oli &#8211; T3 (2019)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">18,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 18,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">15,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 15,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=56\" aria-label=\"Add to cart: &ldquo;Vox Populi - Les Humeurs d&#039;Oli - T3 (2019)&rdquo;\" data-quantity=\"1\" data-product_id=\"56\" data-product_sku=\"9782507056544\" data-price=\"15\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/sacres-champions-les-humeurs-doli-t2-2018\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2018-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Sacr\u00e9s champions !\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Sacr\u00e9s champions ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T2 (2018)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">13,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 13,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=57\" aria-label=\"Add to cart: &ldquo;Sacr\u00e9s champions ! - Les Humeurs d&#039;Oli - T2 (2018)&rdquo;\" data-quantity=\"1\" data-product_id=\"57\" data-product_sku=\"9782507056063\" data-price=\"13\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2018\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/SpaALHeureUS-2018-500-EPUISE-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BD Spa \u00e0 l&#039;heure US - Epuis\u00e9\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Spa \u00e0 l&rsquo;heure US (2018)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/spa-a-lheure-us-2018\/\" aria-label=\"En savoir plus sur &ldquo;Spa \u00e0 l&#039;heure US (2018)&rdquo;\" data-quantity=\"1\" data-product_id=\"62\" data-product_sku=\"9782390101260\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/cest-pas-gagne-les-humeurs-doli-t1-2017\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t<div class=\"wc-block-grid__product-onsale\">\n\t\t\t<span aria-hidden=\"true\">Promo<\/span>\n\t\t\t<span class=\"screen-reader-text\">Produit en promotion<\/span>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/LesHumeursDOli-2017-Couverture-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"C&#039;est pas gagn\u00e9...\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">C&rsquo;est pas gagn\u00e9&#8230; &#8211; Les Humeurs d&rsquo;Oli &#8211; T1 (2017)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/del> <span class=\"screen-reader-text\">Original price was: 16,00&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\">12,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/ins><span class=\"screen-reader-text\">Current price is: 12,00&nbsp;&euro;.<\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=60\" aria-label=\"Add to cart: &ldquo;C&#039;est pas gagn\u00e9... - Les Humeurs d&#039;Oli - T1 (2017)&rdquo;\" data-quantity=\"1\" data-product_id=\"60\" data-product_sku=\"9782507055479\" data-price=\"12\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/de-gre-ou-de-force-le-choix-de-franz-2026\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2026\/05\/DGODF-2026-LeChoixDeFranz-Couverture-Web-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"De gr\u00e9 ou de force - BD - 2026\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">De gr\u00e9 ou de force &#8211; Le choix de Franz (2026)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">20,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"\/boutique\/wp-json\/wp\/v2\/pages\/27?add-to-cart=286\" aria-label=\"Add to cart: &ldquo;De gr\u00e9 ou de force - Le choix de Franz (2026)&rdquo;\" data-quantity=\"1\" data-product_id=\"286\" data-product_sku=\"9782931190333\" data-price=\"20\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button ajax_add_to_cart\">Ajouter au panier<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gare-au-crash-les-humeurs-doli-t6-2022\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2022\/11\/LesHumeursDOli-2022-GareAuCrash-500-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Gare au Crash ! - Les Humeurs d&#039;Oli 2022\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Gare au Crash ! &#8211; Les Humeurs d&rsquo;Oli &#8211; T6 (2022)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">19,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/gare-au-crash-les-humeurs-doli-t6-2022\/\" aria-label=\"En savoir plus sur &ldquo;Gare au Crash ! - Les Humeurs d&#039;Oli - T6 (2022)&rdquo;\" data-quantity=\"1\" data-product_id=\"168\" data-product_sku=\"9782380758702\" data-price=\"19.9\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/hautes-fagnes-contes-et-legendes-2016\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"324\" height=\"486\" src=\"https:\/\/www.humeurs.be\/boutique\/wp-content\/uploads\/2020\/09\/HautesFagnes-ContesEtLegendes-2017-500-EPUISE-324x486.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"BD Hautes Fagnes Contes et L\u00e9gendes\" \/><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Hautes Fagnes &#8211; Contes et L\u00e9gendes (2016)<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\"><span class=\"woocommerce-Price-amount amount\">16,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"wp-block-button wc-block-grid__product-add-to-cart\"><a href=\"https:\/\/www.humeurs.be\/boutique\/produit\/hautes-fagnes-contes-et-legendes-2016\/\" aria-label=\"En savoir plus sur &ldquo;Hautes Fagnes - Contes et L\u00e9gendes (2016)&rdquo;\" data-quantity=\"1\" data-product_id=\"64\" data-product_sku=\"9782390100591\" data-price=\"16\" rel=\"nofollow\" class=\"wp-block-button__link  add_to_cart_button\">Lire la suite<\/a><\/div>\n\t\t\t<\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Shop by Category New In We Recommend Fan Favorites On Sale Best Sellers<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"footnotes":""},"class_list":["post-27","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/pages\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/comments?post=27"}],"version-history":[{"count":1,"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/pages\/27\/revisions"}],"predecessor-version":[{"id":47,"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/pages\/27\/revisions\/47"}],"wp:attachment":[{"href":"https:\/\/www.humeurs.be\/boutique\/wp-json\/wp\/v2\/media?parent=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}